{"id":37950,"date":"2018-12-11T06:03:15","date_gmt":"2018-12-11T06:03:15","guid":{"rendered":"https:\/\/lynk.wpjavo.com\/theme\/?page_id=37950"},"modified":"2022-11-17T13:03:32","modified_gmt":"2022-11-17T13:03:32","slug":"style5-home-mag","status":"publish","type":"page","link":"https:\/\/discovergreece.com.gr\/de\/style5-home-mag\/","title":{"rendered":"Style5 &#8211; Home Mag"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"37950\" class=\"elementor elementor-37950\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f8fa83 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f8fa83\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-db228cc\" data-id=\"db228cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6033e2 elementor-widget elementor-widget-image\" data-id=\"e6033e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"70\" height=\"50\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/09\/ezgif.com-gif-maker-3.gif\" class=\"attachment-jvbpd-tiny size-jvbpd-tiny wp-image-46940\" alt=\"\" srcset=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/09\/ezgif.com-gif-maker-3.gif 70w, https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/09\/ezgif.com-gif-maker-3-18x12.gif 18w\" sizes=\"(max-width: 70px) 100vw, 70px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5dff0a0\" data-id=\"5dff0a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6946935 elementor-widget elementor-widget-heading\" data-id=\"6946935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Discover Greece<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0228476 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0228476\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0ff2ec\" data-id=\"a0ff2ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"menu-type-full_width_center collapse-click elementor-element elementor-element-a2c0425 hide-menu-icon-yes dropdown-effect-fade elementor-widget elementor-widget-jvbpd_nav_menu\" data-dir=\"solid\" data-id=\"a2c0425\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd_nav_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"jvbpd-nav-menu-widget\">\r\n\r\n\t\t\t\t\t\t\t<a href=\"#\" class=\"mobile-opener\" style=\"color:#000;\" data-bs-toggle=\"collapse\" data-bs-target=\"#jvbpd-nav-menu-id-a2c0425\">\r\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t<\/a>\r\n\t\t\t\t<div class=\"menu-wrap\" id=\"jvbpd-nav-menu-id-a2c0425\" data-position-top=\"59px\" data-mobile-bg=\"rgba(0,0,0,0)\">\r\n\t\t\t\t\t\t<div class=\"menu-visit_greece_menu-container\"><ul id=\"menu-visit_greece_menu\" class=\"nav jvbpd-nav jvbpd-nav-menu horizon\"><li id=\"nav-menu-item-45399\" class=\"nav-item main-menu-item  menu-item-even menu-item-depth-0 menu-item menu-item-type-post_type menu-item-object-page menu-item-home\"><a href=\"https:\/\/discovergreece.com.gr\/de\/\" class=\"nav-link menu-link main-menu-link\"><i class=\"nav-icon\"><\/i><span class=\"menu-titles\">Home<\/span><\/a><\/li>\n<li id=\"nav-menu-item-45638\" class=\"nav-item main-menu-item  menu-item-even menu-item-depth-0 menu-item menu-item-type-post_type menu-item-object-page\"><a href=\"https:\/\/discovergreece.com.gr\/de\/v4-home-directory-1\/\" class=\"nav-link menu-link main-menu-link\"><i class=\"nav-icon\"><\/i><span class=\"menu-titles\">Aktivit\u00e4ten<\/span><\/a><\/li>\n<li id=\"nav-menu-item-46720\" class=\"nav-item main-menu-item  menu-item-even menu-item-depth-0 menu-item menu-item-type-custom menu-item-object-custom\"><a href=\"https:\/\/discovergreece.com.gr\/de\/school-program\/\" class=\"nav-link menu-link main-menu-link\"><i class=\"nav-icon\"><\/i><span class=\"menu-titles\">Schulprogramme<\/span><\/a><\/li>\n<li id=\"nav-menu-item-45616\" class=\"nav-item main-menu-item  menu-item-even menu-item-depth-0 menu-item menu-item-type-post_type menu-item-object-page\"><a href=\"https:\/\/discovergreece.com.gr\/de\/success-stories\/\" class=\"nav-link menu-link main-menu-link\"><i class=\"nav-icon\"><\/i><span class=\"menu-titles\">Reiseideen<\/span><\/a><\/li>\n<li id=\"nav-menu-item-45520\" class=\"nav-item main-menu-item  menu-item-even menu-item-depth-0 menu-item menu-item-type-post_type menu-item-object-page\"><a title=\"Karte\" href=\"https:\/\/discovergreece.com.gr\/de\/style4-list-map-2\/\" class=\"nav-link menu-link main-menu-link\"><i class=\"nav-icon\"><\/i><span class=\"menu-titles\">Karte<\/span><\/a><\/li>\n<li id=\"nav-menu-item-45404\" class=\"nav-item main-menu-item  menu-item-even menu-item-depth-0 menu-item menu-item-type-post_type menu-item-object-page\"><a title=\"Bloggen\" href=\"https:\/\/discovergreece.com.gr\/de\/style5-home-mag\/\" class=\"nav-link menu-link main-menu-link\"><i class=\"nav-icon\"><\/i><span class=\"menu-titles\">Bloggen<\/span><\/a><\/li>\n<\/ul><\/div>\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3de5a422 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3de5a422\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c251c16\" data-id=\"c251c16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jvbpd-block-modules elementor-element elementor-element-342b588c elementor-widget elementor-widget-jvbpd-page-block\" data-block-type=\"grid\" data-id=\"342b588c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;module_preview_id&quot;:&quot;0&quot;}\" data-widget_type=\"jvbpd-page-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"post-block-wrap\">\n<div  class=\"javo-shortcode shortcode-jvbpd_block module-layout-type_b header-hide type-post grid-layout colmns-2 pagination- col-mobile- col-tablet-\" >\t\t<div id=\"jvbpd_scd34c8acb68870b16db611a65f3d8745cb\" class=\"shortcode-container fadein\">\r\n\t\t\t\t\t\t\t<div class=\"shortcode-header\">\r\n\t\t\t\t\t<div class=\"shortcode-title\">\r\n\t\t\t\t\t\t<div class=\"title_inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"shortcode-nav\">\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n    <div class=\"shortcode-top-menus float-right\">\r\n                <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n\r\n\t\t\t<div class=\"shortcode-content\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"shortcode-output\">\r\n\t\t\t\t\t<div class=\"output-container\" style=\"\"><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35963\" class=\"elementor elementor-35963 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47324b71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47324b71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5317ef2d\" data-id=\"5317ef2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b08e61 module-card--valign-bottom module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"9b08e61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/Santorini-sunset-in-oia-650x700.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46153\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46153\/\"><\/a>\r\n               \r\n\r\n                                 <h2 class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     Ten tips on how to get to know the real Greece                  <\/h2>\r\n               \r\n                                 <div class=\"module-card__custom_meta1 module-card__content-item elementor-content-item\">\r\n                     \n\/ admin                  <\/div>\r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-top-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35964\" class=\"elementor elementor-35964 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3772a119 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3772a119\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25eb54a3\" data-id=\"25eb54a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-775d670a module-card--valign-bottom module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"775d670a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/Untitled-500x345.png\"><\/div>               <div class=\"module-card__bg-overlay\"><\/div>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\"><\/a>\r\n               \r\n\r\n                                 <h2 class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     Top 10 Reasons Why You can\u2019t Avoid Athens Trip                  <\/h2>\r\n               \r\n                                 <div class=\"module-card__custom_meta1 module-card__content-item elementor-content-item\">\r\n                     \n\/ admin                  <\/div>\r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-top-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35964\" class=\"elementor elementor-35964 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3772a119 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3772a119\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25eb54a3\" data-id=\"25eb54a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-775d670a module-card--valign-bottom module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"775d670a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/Feneos_front-500x400.jpg\"><\/div>               <div class=\"module-card__bg-overlay\"><\/div>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\"><\/a>\r\n               \r\n\r\n                                 <h2 class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     An escape to Corinth mountain area                  <\/h2>\r\n               \r\n                                 <div class=\"module-card__custom_meta1 module-card__content-item elementor-content-item\">\r\n                     \n\/ admin                  <\/div>\r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-top-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><script type=\"text\/javascript\" id=\"js-jvbpd_scd34c8acb68870b16db611a65f3d8745cb\">\njQuery( function($){\ndocument.ajaxurl =\"https:\/\/discovergreece.com.gr\/wp-admin\/admin-ajax.php\";\n$.jvbpd_ajaxShortcode( 'jvbpd_scd34c8acb68870b16db611a65f3d8745cb', {\"load_type\":\"html\",\"title\":\"\",\"subtitle\":\"\",\"css\":\"\",\"author\":null,\"block_type\":\"post\",\"post_type\":\"post\",\"listing_type\":\"\",\"module_type\":\"\",\"module_thumb_size\":\"\",\"count\":3,\"loaded\":3,\"first_count\":\"\",\"taxonomy\":\"\",\"term_id\":\"\",\"term_permalink\":\"\",\"sidebar_filter\":[],\"columns\":2,\"paged\":1,\"pagination\":\"\",\"offset\":\"\",\"thumbnail_size\":\"\",\"order_\":\"DESC\",\"order_by\":\"\",\"filter_by\":\"\",\"filter_style\":\"\",\"loading_style\":\"\",\"custom_filter\":\"\",\"hide_filter\":false,\"primary_color\":\"\",\"primary_font_color\":\"\",\"primary_border_color\":\"\",\"custom_filter_by_post\":\"\",\"post_title_font_color\":\"\",\"post_title_font_size\":false,\"post_title_transform\":\"inherit\",\"post_meta_font_color\":\"\",\"post_describe_font_color\":\"\",\"display_category_tag\":\"\",\"display_post_border\":\"\",\"category_tag_color\":\"#454545\",\"category_tag_hover_color\":\"\",\"slide_wide\":0,\"module_contents_hide\":\"\",\"module_contents_length\":10,\"hide_thumbnail\":\"\",\"hide_avatar\":false,\"hover_style\":\"\",\"is_dashboard\":false,\"show_no_result\":\"\",\"no_results_hide_block\":\"\",\"show_within_date_range\":\"\",\"use_sidebar\":\"\",\"sidebar_pos\":\"\",\"sidebar_filter_product_cat\":\"\",\"module_selector\":\"\",\"post__in\":\"\",\"exclude\":\"\",\"block_module\":\"\",\"block_display_type\":\"grid\",\"carousel\":\"\",\"filter_terms\":\"\",\"masonry\":\"no\",\"listing_package_filter\":\"\",\"module_click_popup\":\"\",\"layout_type\":\"type_b\",\"column_1\":35963,\"column_2\":35964,\"price_min\":null,\"price_max\":null,\"insert_ad\":\"no\",\"ad_pos_order\":0,\"ad_module_id\":0,\"post_block_filter_type\":\"default\",\"lv_listing_filter_by\":\"\",\"custom_filter_by_lv_listing\":\"\",\"custom_filter_lv_listing\":\"\",\"featured_lv_listing\":\"\",\"featured_item\":\"no\",\"rating_type\":\"star\",\"display_rating_grade\":\"\",\"rating_grade_color\":\"\",\"shortcode_name\":\"jvbpd_block\"}); });\n<\/script>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"swiper-pagination swiper-pagination-custom\"><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"shortcode-block-spin-wrap\"><div class=\"shortcode-block-spin1\"><\/div><\/div><div class=\"output-loading\"><\/div><\/div> <!-- \/.Shortcode End jvbpd_scd34c8acb68870b16db611a65f3d8745cb --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-793a2d76 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"793a2d76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-20bd1eeb\" data-id=\"20bd1eeb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jvbpd-block-modules elementor-element elementor-element-d95d935 elementor-widget elementor-widget-jvbpd-page-block\" data-block-type=\"grid\" data-id=\"d95d935\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;module_preview_id&quot;:&quot;0&quot;}\" data-widget_type=\"jvbpd-page-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"post-block-wrap\">\n<div  class=\"javo-shortcode shortcode-jvbpd_block module-layout-type_b filter-general loader-rect type-post grid-layout colmns-2 pagination-prevNext col-mobile- col-tablet-\" >\t\t<div id=\"jvbpd_scd4cde14c8543fcf848a184bd42a0c9526\" class=\"shortcode-container fadein\">\r\n\t\t\t\t\t\t\t<div class=\"shortcode-header\">\r\n\t\t\t\t\t<div class=\"shortcode-title\">\r\n\t\t\t\t\t\t<div class=\"title_inner\">\r\n\t\t\t\t\t\tTips for travel\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"shortcode-nav\">\r\n\t\t\t\t\t\t<ul class=\"shortcode-filter\" data-more=\"More\" data-mobile=\"Filter\" data-tax=\"category\" >\n<li class='filter-nav-item term-all current'>All<\/li>\n<li data-term=\"32\" class=\"filter-nav-item term-id-32\" data-filter=\".cat-32\">Tips<\/li>\n<\/ul>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n    <div class=\"shortcode-top-menus float-right\">\r\n                <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n\r\n\t\t\t<div class=\"shortcode-content\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"shortcode-output\">\r\n\t\t\t\t\t<div class=\"output-container\" style=\"\"><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35958\" class=\"elementor elementor-35958 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50ef90dc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"50ef90dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4e5948\" data-id=\"b4e5948\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4324703b module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"4324703b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/Santorini-sunset-in-oia-400x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46153\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46153\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               Tips            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-157a082f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"157a082f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3c3cde63\" data-id=\"3c3cde63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-19dc1bc9 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"19dc1bc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/46153\/\"  >Ten tips on how to get to know the real Greece<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-field=\"post_date\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-a21416e elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"a21416e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Juni 14, 2022         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-field=\"post_content\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-58fb2a62 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"58fb2a62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            As tempting as it is, to spend your days soaking up the sun, swimming in the clear, warm seas, under the magnificent, ...         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35959\" class=\"elementor elementor-35959 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13b45dc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13b45dc7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23015eef\" data-id=\"23015eef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57ed63c4 module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"57ed63c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/Untitled-150x150.png\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46154\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46154\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               Tips            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-adf996c\" data-id=\"adf996c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-6ccac77d elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"6ccac77d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/46154\/\"  >Top 10 Reasons Why You can\u2019t Avoid Athens Trip<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-field=\"post_date\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-4c2bd29f elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"4c2bd29f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Juni 14, 2022         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35959\" class=\"elementor elementor-35959 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13b45dc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13b45dc7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23015eef\" data-id=\"23015eef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57ed63c4 module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"57ed63c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/kalamata-tapenade1392x780-150x150.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46159\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46159\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               Tips            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-adf996c\" data-id=\"adf996c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-6ccac77d elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"6ccac77d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/46159\/\"  >Kalamata Olive Tapenade<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-field=\"post_date\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-4c2bd29f elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"4c2bd29f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Juni 14, 2022         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><script type=\"text\/javascript\" id=\"js-jvbpd_scd4cde14c8543fcf848a184bd42a0c9526\">\njQuery( function($){\ndocument.ajaxurl =\"https:\/\/discovergreece.com.gr\/wp-admin\/admin-ajax.php\";\n$.jvbpd_ajaxShortcode( 'jvbpd_scd4cde14c8543fcf848a184bd42a0c9526', {\"load_type\":\"html\",\"title\":\"Tips for travel\",\"subtitle\":\"\",\"css\":\"\",\"author\":null,\"block_type\":\"post\",\"post_type\":\"post\",\"listing_type\":\"\",\"module_type\":\"\",\"module_thumb_size\":\"\",\"count\":4,\"loaded\":4,\"first_count\":\"\",\"taxonomy\":\"\",\"term_id\":\"\",\"term_permalink\":\"\",\"sidebar_filter\":[],\"columns\":2,\"paged\":1,\"pagination\":\"prevNext\",\"offset\":\"\",\"thumbnail_size\":\"\",\"order_\":\"DESC\",\"order_by\":\"date\",\"filter_by\":\"category\",\"filter_style\":\"general\",\"loading_style\":\"rect\",\"custom_filter\":32,\"hide_filter\":false,\"primary_color\":\"\",\"primary_font_color\":\"\",\"primary_border_color\":\"\",\"custom_filter_by_post\":1,\"post_title_font_color\":\"\",\"post_title_font_size\":false,\"post_title_transform\":\"inherit\",\"post_meta_font_color\":\"\",\"post_describe_font_color\":\"\",\"display_category_tag\":\"\",\"display_post_border\":\"\",\"category_tag_color\":\"#454545\",\"category_tag_hover_color\":\"\",\"slide_wide\":0,\"module_contents_hide\":\"\",\"module_contents_length\":10,\"hide_thumbnail\":\"\",\"hide_avatar\":false,\"hover_style\":\"\",\"is_dashboard\":false,\"show_no_result\":\"\",\"no_results_hide_block\":\"\",\"show_within_date_range\":\"\",\"use_sidebar\":\"\",\"sidebar_pos\":\"\",\"sidebar_filter_product_cat\":\"\",\"module_selector\":\"\",\"post__in\":\"\",\"exclude\":\"\",\"block_module\":\"\",\"block_display_type\":\"grid\",\"carousel\":\"\",\"filter_terms\":32,\"masonry\":\"no\",\"listing_package_filter\":\"\",\"module_click_popup\":\"\",\"layout_type\":\"type_b\",\"column_1\":35958,\"column_2\":35959,\"price_min\":null,\"price_max\":null,\"insert_ad\":\"no\",\"ad_pos_order\":0,\"ad_module_id\":0,\"post_block_filter_type\":\"default\",\"lv_listing_filter_by\":\"\",\"custom_filter_by_lv_listing\":\"\",\"custom_filter_lv_listing\":\"\",\"featured_lv_listing\":\"\",\"featured_item\":\"no\",\"rating_type\":\"star\",\"display_rating_grade\":\"\",\"rating_grade_color\":\"\",\"shortcode_name\":\"jvbpd_block\"}); });\n<\/script><div class=\"jv-pagination text-start\"><ul class=\"pagination\"><li class=\"page-item disabled\"><a href=\"#\" data-href=\"prevNext|0\" class=\"page-link page-numbers previous\"><i class=\"fa fa-angle-left\"><\/i><\/a><\/li><li class=\"page-item disabled\"><a href=\"#\" data-href=\"prevNext|2\" class=\"page-link page-numbers\"><i class=\"fa fa-angle-right\"><\/i><\/a><\/li><\/ul><\/div>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"swiper-pagination swiper-pagination-custom\"><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"shortcode-block-spin-wrap\"><div class=\"shortcode-block-spin1\"><\/div><\/div><div class=\"output-loading\"><\/div><\/div> <!-- \/.Shortcode End jvbpd_scd4cde14c8543fcf848a184bd42a0c9526 --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jvbpd-block-modules elementor-element elementor-element-51404872 elementor-widget elementor-widget-jvbpd-page-block\" data-block-type=\"grid\" data-id=\"51404872\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;module_preview_id&quot;:&quot;0&quot;}\" data-widget_type=\"jvbpd-page-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"post-block-wrap\">\n<div  class=\"javo-shortcode shortcode-jvbpd_block module-layout-type_b loader-rect type-post grid-layout colmns-2 pagination-prevNextNumber col-mobile- col-tablet-\" >\t\t<div id=\"jvbpd_scdb236bb40d56bc688bfcec688796c28f0\" class=\"shortcode-container fadein\">\r\n\t\t\t\t\t\t\t<div class=\"shortcode-header\">\r\n\t\t\t\t\t<div class=\"shortcode-title\">\r\n\t\t\t\t\t\t<div class=\"title_inner\">\r\n\t\t\t\t\t\tNews\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"shortcode-nav\">\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n    <div class=\"shortcode-top-menus float-right\">\r\n                <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n\r\n\t\t\t<div class=\"shortcode-content\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"shortcode-output\">\r\n\t\t\t\t\t<div class=\"output-container\" style=\"\"><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35958\" class=\"elementor elementor-35958 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50ef90dc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"50ef90dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4e5948\" data-id=\"b4e5948\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4324703b module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"4324703b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/blue-flags-zakynthos-400x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46157\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46157\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               News            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-157a082f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"157a082f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3c3cde63\" data-id=\"3c3cde63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-19dc1bc9 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"19dc1bc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/46157\/\"  >Blue Flags 2022<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-field=\"post_date\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-a21416e elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"a21416e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Juni 14, 2022         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-field=\"post_content\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-58fb2a62 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"58fb2a62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            The\u00a0Hellenic Society for the Protection of Nature\u00a0has announced that, out of a long list of\u00a053\u00a0countries, Greece ...         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><\/div><\/div><script type=\"text\/javascript\" id=\"js-jvbpd_scdb236bb40d56bc688bfcec688796c28f0\">\njQuery( function($){\ndocument.ajaxurl =\"https:\/\/discovergreece.com.gr\/wp-admin\/admin-ajax.php\";\n$.jvbpd_ajaxShortcode( 'jvbpd_scdb236bb40d56bc688bfcec688796c28f0', {\"load_type\":\"html\",\"title\":\"News\",\"subtitle\":\"\",\"css\":\"\",\"author\":null,\"block_type\":\"post\",\"post_type\":\"post\",\"listing_type\":\"\",\"module_type\":\"\",\"module_thumb_size\":\"\",\"count\":4,\"loaded\":4,\"first_count\":\"\",\"taxonomy\":\"\",\"term_id\":\"\",\"term_permalink\":\"\",\"sidebar_filter\":[],\"columns\":2,\"paged\":1,\"pagination\":\"prevNextNumber\",\"offset\":\"\",\"thumbnail_size\":\"\",\"order_\":\"DESC\",\"order_by\":\"date\",\"filter_by\":\"category\",\"filter_style\":\"\",\"loading_style\":\"rect\",\"custom_filter\":31,\"hide_filter\":false,\"primary_color\":\"\",\"primary_font_color\":\"\",\"primary_border_color\":\"\",\"custom_filter_by_post\":1,\"post_title_font_color\":\"\",\"post_title_font_size\":false,\"post_title_transform\":\"inherit\",\"post_meta_font_color\":\"\",\"post_describe_font_color\":\"\",\"display_category_tag\":\"\",\"display_post_border\":\"\",\"category_tag_color\":\"#454545\",\"category_tag_hover_color\":\"\",\"slide_wide\":0,\"module_contents_hide\":\"\",\"module_contents_length\":10,\"hide_thumbnail\":\"\",\"hide_avatar\":false,\"hover_style\":\"\",\"is_dashboard\":false,\"show_no_result\":\"\",\"no_results_hide_block\":\"\",\"show_within_date_range\":\"\",\"use_sidebar\":\"\",\"sidebar_pos\":\"\",\"sidebar_filter_product_cat\":\"\",\"module_selector\":\"\",\"post__in\":\"\",\"exclude\":\"\",\"block_module\":\"\",\"block_display_type\":\"grid\",\"carousel\":\"\",\"filter_terms\":31,\"masonry\":\"no\",\"listing_package_filter\":\"\",\"module_click_popup\":\"\",\"layout_type\":\"type_b\",\"column_1\":35958,\"column_2\":35959,\"price_min\":null,\"price_max\":null,\"insert_ad\":\"no\",\"ad_pos_order\":0,\"ad_module_id\":0,\"post_block_filter_type\":\"default\",\"lv_listing_filter_by\":\"\",\"custom_filter_by_lv_listing\":\"\",\"custom_filter_lv_listing\":\"\",\"featured_lv_listing\":\"\",\"featured_item\":\"no\",\"rating_type\":\"star\",\"display_rating_grade\":\"\",\"rating_grade_color\":\"\",\"shortcode_name\":\"jvbpd_block\"}); });\n<\/script><div class=\"jv-pagination text-center\"><ul class=\"pagination\"><li class=\"page-item disabled\"><a href=\"#\" data-href=\"prevNext|0\" class=\"page-link page-numbers previous\"><i class=\"fa fa-angle-left\"><\/i><\/a><\/li><li class=\"page-item current-number\"><span class=\"current-page\">1<\/span> \/ <span class=\"total-page\">1<\/span><li class=\"page-item disabled\"><a href=\"#\" data-href=\"prevNext|2\" class=\"page-link page-numbers\"><i class=\"fa fa-angle-right\"><\/i><\/a><\/li><\/ul><\/div>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"swiper-pagination swiper-pagination-custom\"><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"shortcode-block-spin-wrap\"><div class=\"shortcode-block-spin1\"><\/div><\/div><div class=\"output-loading\"><\/div><\/div> <!-- \/.Shortcode End jvbpd_scdb236bb40d56bc688bfcec688796c28f0 --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jvbpd-block-modules elementor-element elementor-element-4f7a33a6 elementor-widget elementor-widget-jvbpd-page-block\" data-block-type=\"grid\" data-id=\"4f7a33a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;module_preview_id&quot;:&quot;0&quot;}\" data-widget_type=\"jvbpd-page-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"post-block-wrap\">\n<div  class=\"javo-shortcode shortcode-jvbpd_block module-layout-type_a filter-hide filter-general loader-rect type-post grid-layout colmns-3 pagination-loadmore col-mobile- col-tablet-\" >\t\t<div id=\"jvbpd_scd4d687363c5657f9822ca497711dd7d5e\" class=\"shortcode-container fadein\">\r\n\t\t\t\t\t\t\t<div class=\"shortcode-header\">\r\n\t\t\t\t\t<div class=\"shortcode-title\">\r\n\t\t\t\t\t\t<div class=\"title_inner\">\r\n\t\t\t\t\t\tAll Post\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"shortcode-nav\">\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n    <div class=\"shortcode-top-menus float-right\">\r\n                <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n\r\n\t\t\t<div class=\"shortcode-content\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"shortcode-output\">\r\n\t\t\t\t\t<div class=\"output-container\" style=\"\"><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35289\" class=\"elementor elementor-35289 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44d5895c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"44d5895c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bd2f87a\" data-id=\"3bd2f87a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1042a640 module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"1042a640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/Santorini-sunset-in-oia-400x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46153\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46153\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               Tips            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1de76d82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1de76d82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54da5a9e\" data-id=\"54da5a9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-363a6fe1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"363a6fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/46153\/\"  >Ten tips on how to get to know the real Greece<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f5cc81a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f5cc81a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cdb44ed\" data-id=\"1cdb44ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_date\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-1b657cfc elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"1b657cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Juni 14, 2022         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a6d810f\" data-id=\"3a6d810f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_author\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-67d1a43a elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"67d1a43a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            admin         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49fe2808 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"49fe2808\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4d0c6131\" data-id=\"4d0c6131\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_content\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-21b55dc1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"21b55dc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            As tempting as it is, to spend your days soaking up the sun, swimming in the clear, ...         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35289\" class=\"elementor elementor-35289 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44d5895c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"44d5895c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bd2f87a\" data-id=\"3bd2f87a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1042a640 module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"1042a640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/Untitled-400x250.png\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46154\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46154\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               Tips            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1de76d82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1de76d82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54da5a9e\" data-id=\"54da5a9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-363a6fe1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"363a6fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/46154\/\"  >Top 10 Reasons Why You can\u2019t Avoid Athens Trip<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f5cc81a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f5cc81a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cdb44ed\" data-id=\"1cdb44ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_date\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-1b657cfc elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"1b657cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Juni 14, 2022         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a6d810f\" data-id=\"3a6d810f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_author\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-67d1a43a elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"67d1a43a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            admin         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49fe2808 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"49fe2808\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4d0c6131\" data-id=\"4d0c6131\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_content\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-21b55dc1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"21b55dc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            &nbsp;While in&nbsp;Athens, there are many things to do and many important sites to ...         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35289\" class=\"elementor elementor-35289 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44d5895c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"44d5895c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bd2f87a\" data-id=\"3bd2f87a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1042a640 module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"1042a640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/Feneos_front-400x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46155\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46155\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               Reiseideen            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1de76d82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1de76d82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54da5a9e\" data-id=\"54da5a9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-363a6fe1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"363a6fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/46155\/\"  >An escape to Corinth mountain area<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f5cc81a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f5cc81a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cdb44ed\" data-id=\"1cdb44ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_date\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-1b657cfc elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"1b657cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Juni 14, 2022         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a6d810f\" data-id=\"3a6d810f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_author\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-67d1a43a elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"67d1a43a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            admin         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49fe2808 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"49fe2808\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4d0c6131\" data-id=\"4d0c6131\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_content\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-21b55dc1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"21b55dc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Winter at its Best at a Stone\u2019s Throw from Athens Dreaming of a wintertime escape in ...         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35289\" class=\"elementor elementor-35289 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44d5895c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"44d5895c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bd2f87a\" data-id=\"3bd2f87a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1042a640 module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"1042a640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/05\/3-400x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46156\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46156\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               Reiseideen            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1de76d82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1de76d82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54da5a9e\" data-id=\"54da5a9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-363a6fe1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"363a6fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/46156\/\"  >In the Mountains of Corinth<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f5cc81a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f5cc81a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cdb44ed\" data-id=\"1cdb44ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_date\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-1b657cfc elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"1b657cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Juni 14, 2022         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a6d810f\" data-id=\"3a6d810f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_author\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-67d1a43a elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"67d1a43a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            admin         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49fe2808 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"49fe2808\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4d0c6131\" data-id=\"4d0c6131\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_content\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-21b55dc1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"21b55dc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Less than three hours from Athens by car is an area of stunning natural beauty ...         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35289\" class=\"elementor elementor-35289 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44d5895c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"44d5895c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bd2f87a\" data-id=\"3bd2f87a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1042a640 module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"1042a640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/blue-flags-zakynthos-400x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46157\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46157\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               News            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1de76d82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1de76d82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54da5a9e\" data-id=\"54da5a9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-363a6fe1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"363a6fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/46157\/\"  >Blue Flags 2022<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f5cc81a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f5cc81a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cdb44ed\" data-id=\"1cdb44ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_date\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-1b657cfc elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"1b657cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Juni 14, 2022         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a6d810f\" data-id=\"3a6d810f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_author\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-67d1a43a elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"67d1a43a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            admin         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49fe2808 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"49fe2808\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4d0c6131\" data-id=\"4d0c6131\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_content\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-21b55dc1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"21b55dc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            The\u00a0Hellenic Society for the Protection of Nature\u00a0has announced that, out of a long ...         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35289\" class=\"elementor elementor-35289 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44d5895c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"44d5895c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bd2f87a\" data-id=\"3bd2f87a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1042a640 module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"1042a640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/a0f20d92-074c-467d-8585-40cebde7d62b-view-from-above-of-the-city-of-kalamata-400x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/46158\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/46158\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               Reiseideen            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1de76d82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1de76d82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54da5a9e\" data-id=\"54da5a9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-363a6fe1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"363a6fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/46158\/\"  >Kalamata: a lively summer city worth discovering<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f5cc81a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f5cc81a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cdb44ed\" data-id=\"1cdb44ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_date\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-1b657cfc elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"1b657cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Juni 14, 2022         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a6d810f\" data-id=\"3a6d810f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_author\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-67d1a43a elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"67d1a43a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            admin         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49fe2808 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"49fe2808\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4d0c6131\" data-id=\"4d0c6131\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_content\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-21b55dc1 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"21b55dc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Built on the\u00a0Messinian Gulf\u00a0in southern\u00a0Peloponnese, with the sea being a key component ...         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><script type=\"text\/javascript\" id=\"js-jvbpd_scd4d687363c5657f9822ca497711dd7d5e\">\njQuery( function($){\ndocument.ajaxurl =\"https:\/\/discovergreece.com.gr\/wp-admin\/admin-ajax.php\";\n$.jvbpd_ajaxShortcode( 'jvbpd_scd4d687363c5657f9822ca497711dd7d5e', {\"load_type\":\"html\",\"title\":\"All Post\",\"subtitle\":\"\",\"css\":\"\",\"author\":null,\"block_type\":\"post\",\"post_type\":\"post\",\"listing_type\":\"\",\"module_type\":\"\",\"module_thumb_size\":\"\",\"count\":100,\"loaded\":100,\"first_count\":6,\"taxonomy\":\"\",\"term_id\":\"\",\"term_permalink\":\"\",\"sidebar_filter\":[],\"columns\":3,\"paged\":1,\"pagination\":\"loadmore\",\"offset\":6,\"thumbnail_size\":\"\",\"order_\":\"DESC\",\"order_by\":\"\",\"filter_by\":\"\",\"filter_style\":\"general\",\"loading_style\":\"rect\",\"custom_filter\":\"\",\"hide_filter\":false,\"primary_color\":\"\",\"primary_font_color\":\"\",\"primary_border_color\":\"\",\"custom_filter_by_post\":\"\",\"post_title_font_color\":\"\",\"post_title_font_size\":false,\"post_title_transform\":\"inherit\",\"post_meta_font_color\":\"\",\"post_describe_font_color\":\"\",\"display_category_tag\":\"\",\"display_post_border\":\"\",\"category_tag_color\":\"#454545\",\"category_tag_hover_color\":\"\",\"slide_wide\":0,\"module_contents_hide\":\"\",\"module_contents_length\":10,\"hide_thumbnail\":\"\",\"hide_avatar\":false,\"hover_style\":\"\",\"is_dashboard\":false,\"show_no_result\":\"\",\"no_results_hide_block\":\"\",\"show_within_date_range\":\"\",\"use_sidebar\":\"\",\"sidebar_pos\":\"\",\"sidebar_filter_product_cat\":\"\",\"module_selector\":\"\",\"post__in\":\"\",\"exclude\":\"\",\"block_module\":\"\",\"block_display_type\":\"grid\",\"carousel\":\"\",\"filter_terms\":\"\",\"masonry\":\"no\",\"listing_package_filter\":\"\",\"module_click_popup\":\"\",\"layout_type\":\"type_a\",\"column_1\":35289,\"column_2\":\"\",\"price_min\":null,\"price_max\":null,\"insert_ad\":\"no\",\"ad_pos_order\":0,\"ad_module_id\":0,\"post_block_filter_type\":\"default\",\"lv_listing_filter_by\":\"\",\"custom_filter_by_lv_listing\":\"\",\"custom_filter_lv_listing\":\"\",\"featured_lv_listing\":\"\",\"featured_item\":\"no\",\"rating_type\":\"star\",\"display_rating_grade\":\"\",\"rating_grade_color\":\"\",\"shortcode_name\":\"jvbpd_block\"}); });\n<\/script><div class=\"jv-pagination text-center\"><a href=\"javascript:void(0);\" data-href=\"loadmore|2\" class=\"page-numbers loadmore btn jv-btn-bright outline\">Load More<\/a><div class=\"hidden loading-effect\"><div class=\"spinner-border jv-spinner-border spinner-border-sm text-dark\" role=\"status\"><span class=\"sr-only\">Loading...<\/span><\/div><\/div><\/div>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"swiper-pagination swiper-pagination-custom\"><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"shortcode-block-spin-wrap\"><div class=\"shortcode-block-spin1\"><\/div><\/div><div class=\"output-loading\"><\/div><\/div> <!-- \/.Shortcode End jvbpd_scd4d687363c5657f9822ca497711dd7d5e --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e64f783\" data-id=\"6e64f783\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jvbpd-block-modules elementor-element elementor-element-680500c8 filter-nav-itemgrow elementor-widget elementor-widget-jvbpd-page-block\" data-block-type=\"grid\" data-id=\"680500c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;module_preview_id&quot;:&quot;0&quot;}\" data-widget_type=\"jvbpd-page-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"post-block-wrap\">\n<div  class=\"javo-shortcode shortcode-jvbpd_block module-layout-type_a filter-general loader-rect type-lv_listing grid-layout colmns-1 pagination-number col-mobile- col-tablet-\" >\t\t<div id=\"jvbpd_scd3a586bd025d9b7be522e8f568fa4c4ad\" class=\"shortcode-container fadein\">\r\n\t\t\t\t\t\t\t<div class=\"shortcode-header\">\r\n\t\t\t\t\t<div class=\"shortcode-title\">\r\n\t\t\t\t\t\t<div class=\"title_inner\">\r\n\t\t\t\t\t\tTRavel ideas\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"shortcode-nav\">\r\n\t\t\t\t\t\t<ul class=\"shortcode-filter\" data-more=\"More\" data-mobile=\"Filter\" data-tax=\"listing_category\" >\n<li class='filter-nav-item term-all current'>All<\/li>\n<li data-term=\"124\" class=\"filter-nav-item term-id-124\" data-filter=\".cat-124\">Landtourismuspaket<\/li>\n<\/ul>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n    <div class=\"shortcode-top-menus float-right\">\r\n                <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n\r\n\t\t\t<div class=\"shortcode-content\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"shortcode-output\">\r\n\t\t\t\t\t<div class=\"output-container\" style=\"\"><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35963\" class=\"elementor elementor-35963 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47324b71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47324b71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5317ef2d\" data-id=\"5317ef2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b08e61 module-card--valign-bottom module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"9b08e61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/09\/low-angle-children-sportswear-looking-down-650x700.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/school-program-7-days-in-loutraki\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/school-program-7-days-in-loutraki\/\"><\/a>\r\n               \r\n\r\n                                 <h2 class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     SPORTSCHULPROGRAMM 7 TAGE IN LOUTRAKI                  <\/h2>\r\n               \r\n                                 <div class=\"module-card__custom_meta1 module-card__content-item elementor-content-item\">\r\n                     Corinthia\n\/ admin                  <\/div>\r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-top-left\">\r\n               Landtourismuspaket            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35963\" class=\"elementor elementor-35963 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47324b71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47324b71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5317ef2d\" data-id=\"5317ef2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b08e61 module-card--valign-bottom module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"9b08e61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/07\/AthensGreece-650x700.webp\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/school-program-7-days-in-athens\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/school-program-7-days-in-athens\/\"><\/a>\r\n               \r\n\r\n                                 <h2 class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     SCHOOL PROGRAM 7 DAYS IN ATHENS                  <\/h2>\r\n               \r\n                                 <div class=\"module-card__custom_meta1 module-card__content-item elementor-content-item\">\r\n                     Athens\n\/ admin                  <\/div>\r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-top-left\">\r\n               Landtourismuspaket            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35963\" class=\"elementor elementor-35963 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47324b71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47324b71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5317ef2d\" data-id=\"5317ef2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b08e61 module-card--valign-bottom module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"9b08e61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/arthur-yeti-99w3Senlo4k-unsplash-650x700.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/athens-8-days-in-attica\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/athens-8-days-in-attica\/\"><\/a>\r\n               \r\n\r\n                                 <h2 class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     ATHEN 8 TAGE IN ATTIKA                  <\/h2>\r\n               \r\n                                 <div class=\"module-card__custom_meta1 module-card__content-item elementor-content-item\">\r\n                     Athens\n\/ admin                  <\/div>\r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-top-left\">\r\n               Landtourismuspaket            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><script type=\"text\/javascript\" id=\"js-jvbpd_scd3a586bd025d9b7be522e8f568fa4c4ad\">\njQuery( function($){\ndocument.ajaxurl =\"https:\/\/discovergreece.com.gr\/wp-admin\/admin-ajax.php\";\n$.jvbpd_ajaxShortcode( 'jvbpd_scd3a586bd025d9b7be522e8f568fa4c4ad', {\"load_type\":\"html\",\"title\":\"TRavel ideas\",\"subtitle\":\"\",\"css\":\"\",\"author\":null,\"block_type\":\"post\",\"post_type\":\"lv_listing\",\"listing_type\":\"\",\"module_type\":\"\",\"module_thumb_size\":\"\",\"count\":\"\",\"loaded\":0,\"first_count\":3,\"taxonomy\":\"\",\"term_id\":\"\",\"term_permalink\":\"\",\"sidebar_filter\":[],\"columns\":1,\"paged\":1,\"pagination\":\"number\",\"offset\":3,\"thumbnail_size\":\"\",\"order_\":\"DESC\",\"order_by\":\"\",\"filter_by\":\"listing_category\",\"filter_style\":\"general\",\"loading_style\":\"rect\",\"custom_filter\":124,\"hide_filter\":false,\"primary_color\":\"\",\"primary_font_color\":\"\",\"primary_border_color\":\"\",\"custom_filter_by_post\":1,\"post_title_font_color\":\"\",\"post_title_font_size\":false,\"post_title_transform\":\"inherit\",\"post_meta_font_color\":\"\",\"post_describe_font_color\":\"\",\"display_category_tag\":\"\",\"display_post_border\":\"\",\"category_tag_color\":\"#454545\",\"category_tag_hover_color\":\"\",\"slide_wide\":0,\"module_contents_hide\":\"\",\"module_contents_length\":0,\"hide_thumbnail\":\"\",\"hide_avatar\":false,\"hover_style\":\"\",\"is_dashboard\":false,\"show_no_result\":\"\",\"no_results_hide_block\":\"\",\"show_within_date_range\":\"\",\"use_sidebar\":\"\",\"sidebar_pos\":\"\",\"sidebar_filter_product_cat\":\"\",\"module_selector\":\"\",\"post__in\":\"\",\"exclude\":\"\",\"block_module\":\"\",\"block_display_type\":\"grid\",\"carousel\":\"\",\"filter_terms\":124,\"masonry\":\"no\",\"listing_package_filter\":\"\",\"module_click_popup\":\"\",\"layout_type\":\"type_a\",\"column_1\":35963,\"column_2\":\"\",\"price_min\":null,\"price_max\":null,\"insert_ad\":\"no\",\"ad_pos_order\":0,\"ad_module_id\":0,\"post_block_filter_type\":\"default\",\"lv_listing_filter_by\":\"\",\"custom_filter_by_lv_listing\":\"\",\"custom_filter_lv_listing\":\"\",\"featured_lv_listing\":\"\",\"featured_item\":\"no\",\"rating_type\":\"star\",\"display_rating_grade\":\"\",\"rating_grade_color\":\"\",\"shortcode_name\":\"jvbpd_block\"}); });\n<\/script><div class=\"jv-pagination text-center\"><ul class=\"pagination\"><li class=\"active\" ><span aria-current=\"page\" class=\"page-numbers current\">1<\/span><\/li><li><a class=\"page-numbers\" href=\"http:\/\/|2\">2<\/a><\/li><li><a class=\"page-numbers\" href=\"http:\/\/|3\">3<\/a><\/li><li><a class=\"next page-numbers\" href=\"http:\/\/|2\"><i class=\"post-block-next text-center\"><\/i><\/a><\/li><\/ul><\/div>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"swiper-pagination swiper-pagination-custom\"><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"shortcode-block-spin-wrap\"><div class=\"shortcode-block-spin1\"><\/div><\/div><div class=\"output-loading\"><\/div><\/div> <!-- \/.Shortcode End jvbpd_scd3a586bd025d9b7be522e8f568fa4c4ad --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb7d191 elementor-widget elementor-widget-spacer\" data-id=\"cb7d191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jvbpd-block-modules elementor-element elementor-element-63474f26 filter-nav-itemgrow elementor-widget elementor-widget-jvbpd-page-block\" data-block-type=\"grid\" data-id=\"63474f26\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;module_preview_id&quot;:&quot;0&quot;}\" data-widget_type=\"jvbpd-page-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"post-block-wrap\">\n<div  class=\"javo-shortcode shortcode-jvbpd_block module-layout-type_a filter-general loader-rect type-lv_listing grid-layout colmns-1 pagination-prevNext col-mobile- col-tablet-\" >\t\t<div id=\"jvbpd_scd825b6ba289de71e627cba89d34579b6e\" class=\"shortcode-container fadein\">\r\n\t\t\t\t\t\t\t<div class=\"shortcode-header\">\r\n\t\t\t\t\t<div class=\"shortcode-title\">\r\n\t\t\t\t\t\t<div class=\"title_inner\">\r\n\t\t\t\t\t\tHotels\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"shortcode-nav\">\r\n\t\t\t\t\t\t<ul class=\"shortcode-filter\" data-more=\"More\" data-mobile=\"Filter\" data-tax=\"listing_category\" >\n<li class='filter-nav-item term-all current'>All<\/li>\n<li data-term=\"60\" class=\"filter-nav-item term-id-60\" data-filter=\".cat-60\">Hotels<\/li>\n<\/ul>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n    <div class=\"shortcode-top-menus float-right\">\r\n                <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n\r\n\t\t\t<div class=\"shortcode-content\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"shortcode-output\">\r\n\t\t\t\t\t<div class=\"output-container\" style=\"\"><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35966\" class=\"elementor elementor-35966 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-108b9e40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"108b9e40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7421b092\" data-id=\"7421b092\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c715714 module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"c715714\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/07\/188915749-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/attalos-hotel-athens\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/attalos-hotel-athens\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               Hotels            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-499d6940\" data-id=\"499d6940\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-38558d9f elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"38558d9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/listing\/attalos-hotel-athens\/\"  >Attalos Hotel Athens<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-593a1ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"593a1ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-524bdc6b\" data-id=\"524bdc6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"listing_location\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-d49ccba elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"d49ccba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n                     <div class=\"elementor-icon-wrapper\">\r\n               <div class=\"elementor-icon\">\r\n                  <i class=\"icon jvic-marker\"><\/i>               <\/div>\r\n            <\/div>\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Athen         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-77e97710\" data-id=\"77e97710\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_author\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-59d35a23 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"59d35a23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n                     <div class=\"elementor-icon-wrapper\">\r\n               <div class=\"elementor-icon\">\r\n                  <i class=\"icon jvic-user\"><\/i>               <\/div>\r\n            <\/div>\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            admin         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div data-field=\"rating\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-139e6f13 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"139e6f13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <div class=\"rating-type-image\"><div class=\"module-rating-wrap\"><div class=\"module-ratings\" style=\"width:0%;\"><\/div><\/div><\/div>         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-field=\"post_content\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-370a5b39 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"370a5b39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            The 3-star Hotel Attalos is located in the historic centre of ...         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35966\" class=\"elementor elementor-35966 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-108b9e40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"108b9e40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7421b092\" data-id=\"7421b092\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c715714 module-card--valign-top module-card--scheme-one-block elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"c715714\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/07\/192608046-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/golden-city-hotel\/\"><\/a>\r\n                           <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/golden-city-hotel\/\"><\/a>\r\n               \r\n\r\n               \r\n               \r\n               \r\n               \r\n                                          <div class=\"media-badges cblock-media-bottom-left\">\r\n               Hotels            <\/div>\r\n                        <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-499d6940\" data-id=\"499d6940\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_title\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-38558d9f elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"38558d9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <a href=\"https:\/\/discovergreece.com.gr\/de\/listing\/golden-city-hotel\/\"  >Golden City Hotel<\/a>               <div class=\"d-none\" data-fregment-target=\".badge.ad-listing-badge\">\r\n                  <span class=\"icon-wrap d-inline-block w-100\">\r\n                                       <\/span>\r\n                  <span class=\"bedge-title\">AD<\/span>\r\n               <\/div>\r\n                        <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-593a1ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"593a1ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-524bdc6b\" data-id=\"524bdc6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"listing_location\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-d49ccba elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"d49ccba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n                     <div class=\"elementor-icon-wrapper\">\r\n               <div class=\"elementor-icon\">\r\n                  <i class=\"icon jvic-marker\"><\/i>               <\/div>\r\n            <\/div>\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Athen         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-77e97710\" data-id=\"77e97710\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-field=\"post_author\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-59d35a23 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"59d35a23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n                     <div class=\"elementor-icon-wrapper\">\r\n               <div class=\"elementor-icon\">\r\n                  <i class=\"icon jvic-user\"><\/i>               <\/div>\r\n            <\/div>\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            admin         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div data-field=\"rating\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-139e6f13 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"139e6f13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            <div class=\"rating-type-image\"><div class=\"module-rating-wrap\"><div class=\"module-ratings\" style=\"width:0%;\"><\/div><\/div><\/div>         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-field=\"post_content\" data-hide-empty-value=\"\" class=\"elementor-element elementor-element-370a5b39 elementor-view-default elementor-widget elementor-widget-jvbpd-module-meta\" data-id=\"370a5b39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      \r\n      <div class=\"single-item hstack\">\r\n         \r\n                  <div class=\"item-value\" data-empty-msg=\"No data\">\r\n            Golden City Hotel is centrally located and is an ideal choice ...         <\/div>\r\n               <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><script type=\"text\/javascript\" id=\"js-jvbpd_scd825b6ba289de71e627cba89d34579b6e\">\njQuery( function($){\ndocument.ajaxurl =\"https:\/\/discovergreece.com.gr\/wp-admin\/admin-ajax.php\";\n$.jvbpd_ajaxShortcode( 'jvbpd_scd825b6ba289de71e627cba89d34579b6e', {\"load_type\":\"html\",\"title\":\"Hotels\",\"subtitle\":\"\",\"css\":\"\",\"author\":null,\"block_type\":\"post\",\"post_type\":\"lv_listing\",\"listing_type\":\"\",\"module_type\":\"\",\"module_thumb_size\":\"\",\"count\":2,\"loaded\":2,\"first_count\":\"\",\"taxonomy\":\"\",\"term_id\":\"\",\"term_permalink\":\"\",\"sidebar_filter\":[],\"columns\":1,\"paged\":1,\"pagination\":\"prevNext\",\"offset\":\"\",\"thumbnail_size\":\"\",\"order_\":\"DESC\",\"order_by\":\"\",\"filter_by\":\"listing_category\",\"filter_style\":\"general\",\"loading_style\":\"rect\",\"custom_filter\":60,\"hide_filter\":false,\"primary_color\":\"\",\"primary_font_color\":\"\",\"primary_border_color\":\"\",\"custom_filter_by_post\":1,\"post_title_font_color\":\"\",\"post_title_font_size\":false,\"post_title_transform\":\"inherit\",\"post_meta_font_color\":\"\",\"post_describe_font_color\":\"\",\"display_category_tag\":\"\",\"display_post_border\":\"\",\"category_tag_color\":\"#454545\",\"category_tag_hover_color\":\"\",\"slide_wide\":0,\"module_contents_hide\":\"\",\"module_contents_length\":10,\"hide_thumbnail\":\"\",\"hide_avatar\":false,\"hover_style\":\"\",\"is_dashboard\":false,\"show_no_result\":\"\",\"no_results_hide_block\":\"\",\"show_within_date_range\":\"\",\"use_sidebar\":\"\",\"sidebar_pos\":\"\",\"sidebar_filter_product_cat\":\"\",\"module_selector\":\"\",\"post__in\":\"\",\"exclude\":\"\",\"block_module\":\"\",\"block_display_type\":\"grid\",\"carousel\":\"\",\"filter_terms\":60,\"masonry\":\"no\",\"listing_package_filter\":\"\",\"module_click_popup\":\"\",\"layout_type\":\"type_a\",\"column_1\":35966,\"column_2\":\"\",\"price_min\":null,\"price_max\":null,\"insert_ad\":\"no\",\"ad_pos_order\":0,\"ad_module_id\":0,\"post_block_filter_type\":\"default\",\"lv_listing_filter_by\":\"\",\"custom_filter_by_lv_listing\":\"\",\"custom_filter_lv_listing\":\"\",\"featured_lv_listing\":\"\",\"featured_item\":\"no\",\"rating_type\":\"star\",\"display_rating_grade\":\"\",\"rating_grade_color\":\"\",\"shortcode_name\":\"jvbpd_block\"}); });\n<\/script><div class=\"jv-pagination text-start\"><ul class=\"pagination\"><li class=\"page-item disabled\"><a href=\"#\" data-href=\"prevNext|0\" class=\"page-link page-numbers previous\"><i class=\"fa fa-angle-left\"><\/i><\/a><\/li><li class=\"page-item\"><a href=\"#\" data-href=\"prevNext|2\" class=\"page-link page-numbers prevNext next\"><i class=\"fa fa-angle-right\"><\/i><\/a><\/li><\/ul><\/div>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"swiper-pagination swiper-pagination-custom\"><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"shortcode-block-spin-wrap\"><div class=\"shortcode-block-spin1\"><\/div><\/div><div class=\"output-loading\"><\/div><\/div> <!-- \/.Shortcode End jvbpd_scd825b6ba289de71e627cba89d34579b6e --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ecbbc6 elementor-widget elementor-widget-spacer\" data-id=\"1ecbbc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f54511f elementor-widget elementor-widget-spacer\" data-id=\"5f54511f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Discover Greece Home Activites School Programs Travel Ideas Map Blog SCHOOL PROGRAM 7 DAYS IN ATHENS\ufffc No data \/ admin No data Ten tips on how to get to know the real Greece No data \/ admin No data Top 10 Reasons Why You can\u2019t Avoid Athens Trip No data \/ admin No data Tips [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"class_list":["post-37950","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/pages\/37950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/comments?post=37950"}],"version-history":[{"count":82,"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/pages\/37950\/revisions"}],"predecessor-version":[{"id":47407,"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/pages\/37950\/revisions\/47407"}],"wp:attachment":[{"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/media?parent=37950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}