{"id":37832,"date":"2018-06-08T05:50:21","date_gmt":"2018-06-08T05:50:21","guid":{"rendered":"http:\/\/yellow.wpjavo.com\/travel\/?page_id=33085"},"modified":"2022-11-17T12:24:12","modified_gmt":"2022-11-17T12:24:12","slug":"success-stories","status":"publish","type":"page","link":"https:\/\/discovergreece.com.gr\/de\/success-stories\/","title":{"rendered":"Success Stories"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"37832\" class=\"elementor elementor-37832\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d57b12 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3d57b12\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0840ca5\" data-id=\"0840ca5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ab3c45 elementor-widget elementor-widget-image-carousel\" data-id=\"3ab3c45\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 1\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/1440x550_greek-islands.webp\" alt=\"1440x550_greek-islands\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d3a34b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d3a34b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4fd558\" data-id=\"b4fd558\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8558948 elementor-widget elementor-widget-spacer\" data-id=\"8558948\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa6f480 elementor-widget elementor-widget-heading\" data-id=\"fa6f480\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Book your trip<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d804ee6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d804ee6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c7216b5\" data-id=\"c7216b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ce18e4 elementor-widget elementor-widget-spacer\" data-id=\"3ce18e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31cd6f9 elementor-widget elementor-widget-heading\" data-id=\"31cd6f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">All Packages<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jvbpd-block-modules elementor-element elementor-element-c49c18b elementor-widget elementor-widget-jvbpd-page-block\" data-block-type=\"grid\" data-id=\"c49c18b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;module_preview_id&quot;:&quot;0&quot;}\" data-widget_type=\"jvbpd-page-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"post-block-wrap\">\n<div  class=\"javo-shortcode shortcode-jvbpd_block module-layout-type_a header-hide type-lv_listing grid-layout colmns-3 pagination- col-mobile- col-tablet-\" >\t\t<div id=\"jvbpd_scdbdec15256ddd85c1fab9b449f5fd32a0\" class=\"shortcode-container fadein\">\r\n\t\t\t\t\t\t\t<div class=\"shortcode-header\">\r\n\t\t\t\t\t<div class=\"shortcode-title\">\r\n\t\t\t\t\t\t<div class=\"title_inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"shortcode-nav\">\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n    <div class=\"shortcode-top-menus float-right\">\r\n                <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n\r\n\t\t\t<div class=\"shortcode-content\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"shortcode-output\">\r\n\t\t\t\t\t<div class=\"output-container\" style=\"\"><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/arthur-yeti-99w3Senlo4k-unsplash-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/athens-8-days-in-attica\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/athens-8-days-in-attica\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     ATHEN 8 TAGE IN ATTIKA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/lloyd-dirks-5H3TYR__5mo-unsplash-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/zante-7-days-in-zakynthos\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/zante-7-days-in-zakynthos\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     ZANTE 7 DAYS IN ZAKYNTHOS                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/04\/Trip-to-peloponnese-2-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/sparta-6-days-in-lakonia\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/sparta-6-days-in-lakonia\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     SPARTA 6 DAYS IN LAKONIA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/04\/Trip-to-messinia-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kalamata-6-days-in-messinia\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kalamata-6-days-in-messinia\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     KALAMATA 6 DAYS IN MESSINIA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/04\/Trip-to-kryoneri-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kryoneri-6-days-in-greece\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kryoneri-6-days-in-greece\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     KRYONERI 6 DAYS IN KORINTHIA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><script type=\"text\/javascript\" id=\"js-jvbpd_scdbdec15256ddd85c1fab9b449f5fd32a0\">\njQuery( function($){\ndocument.ajaxurl =\"https:\/\/discovergreece.com.gr\/wp-admin\/admin-ajax.php\";\n$.jvbpd_ajaxShortcode( 'jvbpd_scdbdec15256ddd85c1fab9b449f5fd32a0', {\"load_type\":\"html\",\"title\":\"\",\"subtitle\":\"\",\"css\":\"\",\"author\":null,\"block_type\":\"post\",\"post_type\":\"lv_listing\",\"listing_type\":\"\",\"module_type\":\"\",\"module_thumb_size\":\"\",\"count\":6,\"loaded\":6,\"first_count\":\"\",\"taxonomy\":\"\",\"term_id\":\"\",\"term_permalink\":\"\",\"sidebar_filter\":[],\"columns\":3,\"paged\":1,\"pagination\":\"\",\"offset\":\"\",\"thumbnail_size\":\"\",\"order_\":\"DESC\",\"order_by\":\"\",\"filter_by\":\"listing_category\",\"filter_style\":\"\",\"loading_style\":\"\",\"custom_filter\":\"98,99\",\"hide_filter\":false,\"primary_color\":\"\",\"primary_font_color\":\"\",\"primary_border_color\":\"\",\"custom_filter_by_post\":1,\"post_title_font_color\":\"\",\"post_title_font_size\":false,\"post_title_transform\":\"inherit\",\"post_meta_font_color\":\"\",\"post_describe_font_color\":\"\",\"display_category_tag\":\"\",\"display_post_border\":\"\",\"category_tag_color\":\"#454545\",\"category_tag_hover_color\":\"\",\"slide_wide\":0,\"module_contents_hide\":\"\",\"module_contents_length\":10,\"hide_thumbnail\":\"\",\"hide_avatar\":false,\"hover_style\":\"\",\"is_dashboard\":false,\"show_no_result\":\"\",\"no_results_hide_block\":\"\",\"show_within_date_range\":\"\",\"use_sidebar\":\"\",\"sidebar_pos\":\"\",\"sidebar_filter_product_cat\":\"\",\"module_selector\":\"\",\"post__in\":\"\",\"exclude\":\"\",\"block_module\":\"\",\"block_display_type\":\"grid\",\"carousel\":\"\",\"filter_terms\":\"98,99\",\"masonry\":\"no\",\"listing_package_filter\":\"\",\"module_click_popup\":\"\",\"layout_type\":\"type_a\",\"column_1\":10168,\"column_2\":\"\",\"price_min\":null,\"price_max\":null,\"insert_ad\":\"no\",\"ad_pos_order\":0,\"ad_module_id\":0,\"post_block_filter_type\":\"default\",\"lv_listing_filter_by\":\"\",\"custom_filter_by_lv_listing\":\"\",\"custom_filter_lv_listing\":\"\",\"featured_lv_listing\":\"\",\"featured_item\":\"no\",\"rating_type\":\"star\",\"display_rating_grade\":\"\",\"rating_grade_color\":\"\",\"shortcode_name\":\"jvbpd_block\"}); });\n<\/script>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"swiper-pagination swiper-pagination-custom\"><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"shortcode-block-spin-wrap\"><div class=\"shortcode-block-spin1\"><\/div><\/div><div class=\"output-loading\"><\/div><\/div> <!-- \/.Shortcode End jvbpd_scdbdec15256ddd85c1fab9b449f5fd32a0 --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ea92da elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ea92da\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7efa125\" data-id=\"7efa125\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f103de2 elementor-widget elementor-widget-heading\" data-id=\"f103de2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ausfl\u00fcge\u00a0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a23bd10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a23bd10\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-46955fb\" data-id=\"46955fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-152b720 elementor-widget elementor-widget-image\" data-id=\"152b720\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3968b49 elementor-widget elementor-widget-heading\" data-id=\"3968b49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Add Your Heading Text Here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-a114007\" data-id=\"a114007\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60f3844 elementor-widget elementor-widget-image\" data-id=\"60f3844\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83a85c8 elementor-widget elementor-widget-heading\" data-id=\"83a85c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Add Your Heading Text Here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-83cbbdc\" data-id=\"83cbbdc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfb6bb6 elementor-widget elementor-widget-image\" data-id=\"bfb6bb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c0f568 elementor-widget elementor-widget-heading\" data-id=\"7c0f568\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Add Your Heading Text Here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2c33675\" data-id=\"2c33675\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eba6541 elementor-widget elementor-widget-image\" data-id=\"eba6541\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea2d785 elementor-widget elementor-widget-heading\" data-id=\"ea2d785\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Add Your Heading Text Here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-e6f9988\" data-id=\"e6f9988\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-665db27 elementor-widget elementor-widget-image\" data-id=\"665db27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf6e99 elementor-widget elementor-widget-heading\" data-id=\"4bf6e99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Add Your Heading Text Here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-592a14b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"592a14b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-45eb993\" data-id=\"45eb993\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5a3a75 elementor-widget elementor-widget-image\" data-id=\"b5a3a75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46b7c96 elementor-widget elementor-widget-heading\" data-id=\"46b7c96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Add Your Heading Text Here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-f2e16c0\" data-id=\"f2e16c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a04db82 elementor-widget elementor-widget-image\" data-id=\"a04db82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b78963c elementor-widget elementor-widget-heading\" data-id=\"b78963c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Add Your Heading Text Here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-646b2ee\" data-id=\"646b2ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d63d900 elementor-widget elementor-widget-image\" data-id=\"d63d900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a67a37 elementor-widget elementor-widget-heading\" data-id=\"0a67a37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Add Your Heading Text Here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-ea538c6\" data-id=\"ea538c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcd9743 elementor-widget elementor-widget-image\" data-id=\"fcd9743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca72c7 elementor-widget elementor-widget-heading\" data-id=\"2ca72c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Add Your Heading Text Here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-3286bfc\" data-id=\"3286bfc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ff970c elementor-widget elementor-widget-image\" data-id=\"7ff970c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/discovergreece.com.gr\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2320df elementor-widget elementor-widget-heading\" data-id=\"b2320df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Add Your Heading Text Here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e46c3e1 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e46c3e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d8590e\" data-id=\"5d8590e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d03112d elementor-widget elementor-widget-spacer\" data-id=\"d03112d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0d282d elementor-widget elementor-widget-heading\" data-id=\"e0d282d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Athen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jvbpd-block-modules elementor-element elementor-element-4dcb2ef elementor-widget elementor-widget-jvbpd-page-block\" data-block-type=\"grid\" data-id=\"4dcb2ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;module_preview_id&quot;:&quot;0&quot;}\" data-widget_type=\"jvbpd-page-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"post-block-wrap\">\n<div  class=\"javo-shortcode shortcode-jvbpd_block module-layout-type_a header-hide type-lv_listing grid-layout colmns-3 pagination- col-mobile- col-tablet-\" >\t\t<div id=\"jvbpd_scdb7c3b34a401b0c52cfd36c5065d03793\" class=\"shortcode-container fadein\">\r\n\t\t\t\t\t\t\t<div class=\"shortcode-header\">\r\n\t\t\t\t\t<div class=\"shortcode-title\">\r\n\t\t\t\t\t\t<div class=\"title_inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"shortcode-nav\">\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n    <div class=\"shortcode-top-menus float-right\">\r\n                <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n\r\n\t\t\t<div class=\"shortcode-content\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"shortcode-output\">\r\n\t\t\t\t\t<div class=\"output-container\" style=\"\"><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/arthur-yeti-99w3Senlo4k-unsplash-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/athens-8-days-in-attica\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/athens-8-days-in-attica\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     ATHEN 8 TAGE IN ATTIKA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><script type=\"text\/javascript\" id=\"js-jvbpd_scdb7c3b34a401b0c52cfd36c5065d03793\">\njQuery( function($){\ndocument.ajaxurl =\"https:\/\/discovergreece.com.gr\/wp-admin\/admin-ajax.php\";\n$.jvbpd_ajaxShortcode( 'jvbpd_scdb7c3b34a401b0c52cfd36c5065d03793', {\"load_type\":\"html\",\"title\":\"\",\"subtitle\":\"\",\"css\":\"\",\"author\":null,\"block_type\":\"post\",\"post_type\":\"lv_listing\",\"listing_type\":\"\",\"module_type\":\"\",\"module_thumb_size\":\"\",\"count\":6,\"loaded\":6,\"first_count\":\"\",\"taxonomy\":\"\",\"term_id\":\"\",\"term_permalink\":\"\",\"sidebar_filter\":[],\"columns\":3,\"paged\":1,\"pagination\":\"\",\"offset\":\"\",\"thumbnail_size\":\"\",\"order_\":\"DESC\",\"order_by\":\"\",\"filter_by\":\"listing_category\",\"filter_style\":\"\",\"loading_style\":\"\",\"custom_filter\":98,\"hide_filter\":false,\"primary_color\":\"\",\"primary_font_color\":\"\",\"primary_border_color\":\"\",\"custom_filter_by_post\":1,\"post_title_font_color\":\"\",\"post_title_font_size\":false,\"post_title_transform\":\"inherit\",\"post_meta_font_color\":\"\",\"post_describe_font_color\":\"\",\"display_category_tag\":\"\",\"display_post_border\":\"\",\"category_tag_color\":\"#454545\",\"category_tag_hover_color\":\"\",\"slide_wide\":0,\"module_contents_hide\":\"\",\"module_contents_length\":10,\"hide_thumbnail\":\"\",\"hide_avatar\":false,\"hover_style\":\"\",\"is_dashboard\":false,\"show_no_result\":\"\",\"no_results_hide_block\":\"\",\"show_within_date_range\":\"\",\"use_sidebar\":\"\",\"sidebar_pos\":\"\",\"sidebar_filter_product_cat\":\"\",\"module_selector\":\"\",\"post__in\":\"\",\"exclude\":\"\",\"block_module\":\"\",\"block_display_type\":\"grid\",\"carousel\":\"\",\"filter_terms\":98,\"masonry\":\"no\",\"listing_package_filter\":\"\",\"module_click_popup\":\"\",\"layout_type\":\"type_a\",\"column_1\":10168,\"column_2\":\"\",\"price_min\":null,\"price_max\":null,\"insert_ad\":\"no\",\"ad_pos_order\":0,\"ad_module_id\":0,\"post_block_filter_type\":\"default\",\"lv_listing_filter_by\":\"\",\"custom_filter_by_lv_listing\":\"\",\"custom_filter_lv_listing\":\"\",\"featured_lv_listing\":\"\",\"featured_item\":\"no\",\"rating_type\":\"star\",\"display_rating_grade\":\"\",\"rating_grade_color\":\"\",\"shortcode_name\":\"jvbpd_block\"}); });\n<\/script>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"swiper-pagination swiper-pagination-custom\"><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"shortcode-block-spin-wrap\"><div class=\"shortcode-block-spin1\"><\/div><\/div><div class=\"output-loading\"><\/div><\/div> <!-- \/.Shortcode End jvbpd_scdb7c3b34a401b0c52cfd36c5065d03793 --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8c8d18 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8c8d18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07b38bb\" data-id=\"07b38bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e87d72 elementor-widget elementor-widget-spacer\" data-id=\"4e87d72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0ea453 elementor-widget elementor-widget-heading\" data-id=\"d0ea453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Peloponnes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jvbpd-block-modules elementor-element elementor-element-d1ce8e9 elementor-widget elementor-widget-jvbpd-page-block\" data-block-type=\"grid\" data-id=\"d1ce8e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;module_preview_id&quot;:&quot;0&quot;}\" data-widget_type=\"jvbpd-page-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"post-block-wrap\">\n<div  class=\"javo-shortcode shortcode-jvbpd_block module-layout-type_a header-hide type-lv_listing grid-layout colmns-3 pagination- col-mobile- col-tablet-\" >\t\t<div id=\"jvbpd_scdb0c3729334514e7ad7ef1688f25fb434\" class=\"shortcode-container fadein\">\r\n\t\t\t\t\t\t\t<div class=\"shortcode-header\">\r\n\t\t\t\t\t<div class=\"shortcode-title\">\r\n\t\t\t\t\t\t<div class=\"title_inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"shortcode-nav\">\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n    <div class=\"shortcode-top-menus float-right\">\r\n                <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n\r\n\t\t\t<div class=\"shortcode-content\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"shortcode-output\">\r\n\t\t\t\t\t<div class=\"output-container\" style=\"\"><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/lloyd-dirks-5H3TYR__5mo-unsplash-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/zante-7-days-in-zakynthos\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/zante-7-days-in-zakynthos\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     ZANTE 7 DAYS IN ZAKYNTHOS                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/04\/Trip-to-peloponnese-2-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/sparta-6-days-in-lakonia\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/sparta-6-days-in-lakonia\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     SPARTA 6 DAYS IN LAKONIA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/04\/Trip-to-messinia-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kalamata-6-days-in-messinia\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kalamata-6-days-in-messinia\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     KALAMATA 6 DAYS IN MESSINIA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/04\/Trip-to-kryoneri-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kryoneri-6-days-in-greece\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kryoneri-6-days-in-greece\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     KRYONERI 6 DAYS IN KORINTHIA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><script type=\"text\/javascript\" id=\"js-jvbpd_scdb0c3729334514e7ad7ef1688f25fb434\">\njQuery( function($){\ndocument.ajaxurl =\"https:\/\/discovergreece.com.gr\/wp-admin\/admin-ajax.php\";\n$.jvbpd_ajaxShortcode( 'jvbpd_scdb0c3729334514e7ad7ef1688f25fb434', {\"load_type\":\"html\",\"title\":\"\",\"subtitle\":\"\",\"css\":\"\",\"author\":null,\"block_type\":\"post\",\"post_type\":\"lv_listing\",\"listing_type\":\"\",\"module_type\":\"\",\"module_thumb_size\":\"\",\"count\":6,\"loaded\":6,\"first_count\":\"\",\"taxonomy\":\"\",\"term_id\":\"\",\"term_permalink\":\"\",\"sidebar_filter\":[],\"columns\":3,\"paged\":1,\"pagination\":\"\",\"offset\":\"\",\"thumbnail_size\":\"\",\"order_\":\"DESC\",\"order_by\":\"\",\"filter_by\":\"listing_category\",\"filter_style\":\"\",\"loading_style\":\"\",\"custom_filter\":99,\"hide_filter\":false,\"primary_color\":\"\",\"primary_font_color\":\"\",\"primary_border_color\":\"\",\"custom_filter_by_post\":1,\"post_title_font_color\":\"\",\"post_title_font_size\":false,\"post_title_transform\":\"inherit\",\"post_meta_font_color\":\"\",\"post_describe_font_color\":\"\",\"display_category_tag\":\"\",\"display_post_border\":\"\",\"category_tag_color\":\"#454545\",\"category_tag_hover_color\":\"\",\"slide_wide\":0,\"module_contents_hide\":\"\",\"module_contents_length\":10,\"hide_thumbnail\":\"\",\"hide_avatar\":false,\"hover_style\":\"\",\"is_dashboard\":false,\"show_no_result\":\"\",\"no_results_hide_block\":\"\",\"show_within_date_range\":\"\",\"use_sidebar\":\"\",\"sidebar_pos\":\"\",\"sidebar_filter_product_cat\":\"\",\"module_selector\":\"\",\"post__in\":\"\",\"exclude\":\"\",\"block_module\":\"\",\"block_display_type\":\"grid\",\"carousel\":\"\",\"filter_terms\":99,\"masonry\":\"no\",\"listing_package_filter\":\"\",\"module_click_popup\":\"\",\"layout_type\":\"type_a\",\"column_1\":10168,\"column_2\":\"\",\"price_min\":null,\"price_max\":null,\"insert_ad\":\"no\",\"ad_pos_order\":0,\"ad_module_id\":0,\"post_block_filter_type\":\"default\",\"lv_listing_filter_by\":\"\",\"custom_filter_by_lv_listing\":\"\",\"custom_filter_lv_listing\":\"\",\"featured_lv_listing\":\"\",\"featured_item\":\"no\",\"rating_type\":\"star\",\"display_rating_grade\":\"\",\"rating_grade_color\":\"\",\"shortcode_name\":\"jvbpd_block\"}); });\n<\/script>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"swiper-pagination swiper-pagination-custom\"><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"shortcode-block-spin-wrap\"><div class=\"shortcode-block-spin1\"><\/div><\/div><div class=\"output-loading\"><\/div><\/div> <!-- \/.Shortcode End jvbpd_scdb0c3729334514e7ad7ef1688f25fb434 --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f074a9 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f074a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56b8a25\" data-id=\"56b8a25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-694d940 elementor-widget elementor-widget-spacer\" data-id=\"694d940\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6afab6a elementor-widget elementor-widget-heading\" data-id=\"6afab6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Peloponnes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jvbpd-block-modules elementor-element elementor-element-0fc8781 elementor-widget elementor-widget-jvbpd-page-block\" data-block-type=\"grid\" data-id=\"0fc8781\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;module_preview_id&quot;:&quot;0&quot;}\" data-widget_type=\"jvbpd-page-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"post-block-wrap\">\n<div  class=\"javo-shortcode shortcode-jvbpd_block module-layout-type_a header-hide type-lv_listing grid-layout colmns-3 pagination- col-mobile- col-tablet-\" >\t\t<div id=\"jvbpd_scd94b52460f715ac4d327e8b35c5b48c16\" class=\"shortcode-container fadein\">\r\n\t\t\t\t\t\t\t<div class=\"shortcode-header\">\r\n\t\t\t\t\t<div class=\"shortcode-title\">\r\n\t\t\t\t\t\t<div class=\"title_inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"shortcode-nav\">\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n    <div class=\"shortcode-top-menus float-right\">\r\n                <\/div>\r\n    <div class=\"clearfix\"><\/div>\r\n\r\n\t\t\t<div class=\"shortcode-content\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"shortcode-output\">\r\n\t\t\t\t\t<div class=\"output-container\" style=\"\"><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/06\/lloyd-dirks-5H3TYR__5mo-unsplash-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/zante-7-days-in-zakynthos\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/zante-7-days-in-zakynthos\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     ZANTE 7 DAYS IN ZAKYNTHOS                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/04\/Trip-to-peloponnese-2-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/sparta-6-days-in-lakonia\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/sparta-6-days-in-lakonia\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     SPARTA 6 DAYS IN LAKONIA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/04\/Trip-to-messinia-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kalamata-6-days-in-messinia\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kalamata-6-days-in-messinia\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     KALAMATA 6 DAYS IN MESSINIA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"column-item\"><div class=\"module-item\" >\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10168\" class=\"elementor elementor-10168 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8e7729 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8e7729\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"jvfrm-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122058a\" data-id=\"122058a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a377f54 module-card--scheme-two-block module-card--layout-image-above elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-jvbpd-module-card\" data-id=\"a377f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jvbpd-module-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n      <div  class=\"module-card\">\r\n\r\n                     <div class=\"module-card__bg-wrapper\">\r\n               <div class=\"module-card__bg elementor-bg lazyload\" data-bg=\"https:\/\/discovergreece.com.gr\/wp-content\/uploads\/2022\/04\/Trip-to-kryoneri-250x250.jpg\"><\/div>               <a class=\"module-card__bg-overlay\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kryoneri-6-days-in-greece\/\"><\/a>\r\n                           <div class=\"media-badges cblock-media-bottom-left\">\r\n                           <\/div>\r\n                        <\/div>\r\n                              <div class=\"module-card__content\">\r\n               <a class=\"one-block-whole-link\" href=\"https:\/\/discovergreece.com.gr\/de\/listing\/kryoneri-6-days-in-greece\/\"><\/a>\r\n               \r\n\r\n                                 <div class=\"module-card__title module-card__content-item elementor-content-item\">\r\n                     KRYONERI 6 DAYS IN KORINTHIA                  <\/div>\r\n               \r\n               \r\n               \r\n               \r\n                                          <\/div>\r\n                  <\/div>\r\n      \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><script type=\"text\/javascript\" id=\"js-jvbpd_scd94b52460f715ac4d327e8b35c5b48c16\">\njQuery( function($){\ndocument.ajaxurl =\"https:\/\/discovergreece.com.gr\/wp-admin\/admin-ajax.php\";\n$.jvbpd_ajaxShortcode( 'jvbpd_scd94b52460f715ac4d327e8b35c5b48c16', {\"load_type\":\"html\",\"title\":\"\",\"subtitle\":\"\",\"css\":\"\",\"author\":null,\"block_type\":\"post\",\"post_type\":\"lv_listing\",\"listing_type\":\"\",\"module_type\":\"\",\"module_thumb_size\":\"\",\"count\":6,\"loaded\":6,\"first_count\":\"\",\"taxonomy\":\"\",\"term_id\":\"\",\"term_permalink\":\"\",\"sidebar_filter\":[],\"columns\":3,\"paged\":1,\"pagination\":\"\",\"offset\":\"\",\"thumbnail_size\":\"\",\"order_\":\"DESC\",\"order_by\":\"\",\"filter_by\":\"listing_category\",\"filter_style\":\"\",\"loading_style\":\"\",\"custom_filter\":99,\"hide_filter\":false,\"primary_color\":\"\",\"primary_font_color\":\"\",\"primary_border_color\":\"\",\"custom_filter_by_post\":1,\"post_title_font_color\":\"\",\"post_title_font_size\":false,\"post_title_transform\":\"inherit\",\"post_meta_font_color\":\"\",\"post_describe_font_color\":\"\",\"display_category_tag\":\"\",\"display_post_border\":\"\",\"category_tag_color\":\"#454545\",\"category_tag_hover_color\":\"\",\"slide_wide\":0,\"module_contents_hide\":\"\",\"module_contents_length\":10,\"hide_thumbnail\":\"\",\"hide_avatar\":false,\"hover_style\":\"\",\"is_dashboard\":false,\"show_no_result\":\"\",\"no_results_hide_block\":\"\",\"show_within_date_range\":\"\",\"use_sidebar\":\"\",\"sidebar_pos\":\"\",\"sidebar_filter_product_cat\":\"\",\"module_selector\":\"\",\"post__in\":\"\",\"exclude\":\"\",\"block_module\":\"\",\"block_display_type\":\"grid\",\"carousel\":\"\",\"filter_terms\":99,\"masonry\":\"no\",\"listing_package_filter\":\"\",\"module_click_popup\":\"\",\"layout_type\":\"type_a\",\"column_1\":10168,\"column_2\":\"\",\"price_min\":null,\"price_max\":null,\"insert_ad\":\"no\",\"ad_pos_order\":0,\"ad_module_id\":0,\"post_block_filter_type\":\"default\",\"lv_listing_filter_by\":\"\",\"custom_filter_by_lv_listing\":\"\",\"custom_filter_lv_listing\":\"\",\"featured_lv_listing\":\"\",\"featured_item\":\"no\",\"rating_type\":\"star\",\"display_rating_grade\":\"\",\"rating_grade_color\":\"\",\"shortcode_name\":\"jvbpd_block\"}); });\n<\/script>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"swiper-pagination swiper-pagination-custom\"><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<div class=\"shortcode-block-spin-wrap\"><div class=\"shortcode-block-spin1\"><\/div><\/div><div class=\"output-loading\"><\/div><\/div> <!-- \/.Shortcode End jvbpd_scd94b52460f715ac4d327e8b35c5b48c16 --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-554d4535 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"554d4535\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Book your trip All Packages No data ATHENS 8 DAYS IN ATTICA No data ZANTE 7 DAYS IN ZAKYNTHOS No data SPARTA 6 DAYS IN LAKONIA No data KALAMATA 6 DAYS IN MESSINIA No data KRYONERI 6 DAYS IN KORINTHIA Excursions\u00a0 Add Your Heading Text Here Add Your Heading Text Here Add Your Heading Text [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"class_list":["post-37832","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/pages\/37832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/comments?post=37832"}],"version-history":[{"count":40,"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/pages\/37832\/revisions"}],"predecessor-version":[{"id":47317,"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/pages\/37832\/revisions\/47317"}],"wp:attachment":[{"href":"https:\/\/discovergreece.com.gr\/de\/wp-json\/wp\/v2\/media?parent=37832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}